{"id":990,"date":"2020-02-19T12:42:14","date_gmt":"2020-02-19T12:42:14","guid":{"rendered":"http:\/\/www.frecan.es\/blog\/?p=990"},"modified":"2023-02-22T11:35:30","modified_gmt":"2023-02-22T11:35:30","slug":"salida-de-humos","status":"publish","type":"post","link":"https:\/\/www.frecan.es\/blog\/salida-de-humos\/","title":{"rendered":"Un problema en el que nos podemos encontrar es que no tengamos una salida de humos para poner una campana de extraccio\u0301n"},"content":{"rendered":"<h2 style=\"color: #949494; font-size: 24px; line-height: 26px; margin-top: -20px;\">Te damos la solucio\u0301n que dara\u0301 vida a muchas cocinas.<\/h2>\n<p><!--more--><\/p>\n<p><strong>\u00bfSabes que en Frecan todas las campanas se pueden instalar tanto con salida al exterior o sin salida, es decir, con sistema de recirculaci\u00f3n?<\/strong><\/p>\n<p>Generalmente la gran mayori\u0301a de cocinas tienen salida de humos exterior, pero nos podemos encontrar en algunos casos que que no haya. En Frecan, te facilitamos todas las opciones, dependiendo de las condiciones funcionales y est\u00e9ticas de tu cocina. La ubicaci\u00f3n de la salida de humo dejar\u00e1 de ser un elemento limitante pudiendo dise\u00f1ar con total libertad, haciendo aquello que siempre hab\u00eda deseado hacer.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-2928\" src=\"https:\/\/www.frecan.es\/blog\/wp-content\/uploads\/2017\/02\/cocinas-sin-salida-de-humo-recirculacion-eficiente-1.jpg\" alt=\"Frecan, campana sin salida de humos. Recirculaci\u00f3n eficiente\" width=\"2016\" height=\"1346\" srcset=\"https:\/\/www.frecan.es\/blog\/wp-content\/uploads\/2017\/02\/cocinas-sin-salida-de-humo-recirculacion-eficiente-1.jpg 2016w, https:\/\/www.frecan.es\/blog\/wp-content\/uploads\/2017\/02\/cocinas-sin-salida-de-humo-recirculacion-eficiente-1-300x200.jpg 300w, https:\/\/www.frecan.es\/blog\/wp-content\/uploads\/2017\/02\/cocinas-sin-salida-de-humo-recirculacion-eficiente-1-768x513.jpg 768w, https:\/\/www.frecan.es\/blog\/wp-content\/uploads\/2017\/02\/cocinas-sin-salida-de-humo-recirculacion-eficiente-1-1024x684.jpg 1024w, https:\/\/www.frecan.es\/blog\/wp-content\/uploads\/2017\/02\/cocinas-sin-salida-de-humo-recirculacion-eficiente-1-500x334.jpg 500w, https:\/\/www.frecan.es\/blog\/wp-content\/uploads\/2017\/02\/cocinas-sin-salida-de-humo-recirculacion-eficiente-1-800x534.jpg 800w, https:\/\/www.frecan.es\/blog\/wp-content\/uploads\/2017\/02\/cocinas-sin-salida-de-humo-recirculacion-eficiente-1-1280x855.jpg 1280w\" sizes=\"auto, (max-width: 2016px) 100vw, 2016px\" \/><\/p>\n<p>Con <a href=\"https:\/\/www.frecan.es\/campanas\/recirculacion\/\">los sistemas de recirculaci\u00f3n<\/a>, no es un problema que no cuentes con un sistema de ventilaci\u00f3n adecuado o sin salida al exterior, <a style=\"font-family: inherit; color: inherit !important; text-decoration: none;\" href=\"https:\/\/mytopface.com\/when-and-how-to-clean-and-disinfect-your-home\/\">affordable house cleaning options <\/a>. Incluso si la instalaci\u00f3n de salida de aire, tiene p\u00e9rdidas de aire de m\u00e1s de un 40% para una \u00f3ptima aspiraci\u00f3n, tambi\u00e9n recomendamos instalar un sistema de recirculaci\u00f3n<\/p>\n<h3>Pero, c\u00f3mo funciona una campana de recirculaci\u00f3n<\/h3>\n<p>El funcionamiento de una <a href=\"https:\/\/www.frecan.es\/campanas\/recirculacion\/\">campana de recirculaci\u00f3n <\/a>es muy sencillo. Se encarga de absorber el aire, que es limpiado mediante un filtro antigrasa y un filtro de carb\u00f3n activo con el que se consigue eliminar todos los malos olores. De esta forma se devuelve el aire a la cocina totalmente libre de olores, al\u00e9rgenos y sustancias contaminantes. Al limpiar el aire mediante los filtros y devolverlo no se necesita ninguna salida de humos al exterior de la vivienda.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-2756\" src=\"https:\/\/www.frecan.es\/blog\/wp-content\/uploads\/2019\/10\/tecnicas-plasma-frecan-casas-pasivas.jpg\" alt=\"Filtro plasma Frecan, casas pasivas\" width=\"1200\" height=\"510\" srcset=\"https:\/\/www.frecan.es\/blog\/wp-content\/uploads\/2019\/10\/tecnicas-plasma-frecan-casas-pasivas.jpg 1200w, https:\/\/www.frecan.es\/blog\/wp-content\/uploads\/2019\/10\/tecnicas-plasma-frecan-casas-pasivas-300x128.jpg 300w, https:\/\/www.frecan.es\/blog\/wp-content\/uploads\/2019\/10\/tecnicas-plasma-frecan-casas-pasivas-768x326.jpg 768w, https:\/\/www.frecan.es\/blog\/wp-content\/uploads\/2019\/10\/tecnicas-plasma-frecan-casas-pasivas-1024x435.jpg 1024w, https:\/\/www.frecan.es\/blog\/wp-content\/uploads\/2019\/10\/tecnicas-plasma-frecan-casas-pasivas-500x213.jpg 500w, https:\/\/www.frecan.es\/blog\/wp-content\/uploads\/2019\/10\/tecnicas-plasma-frecan-casas-pasivas-800x340.jpg 800w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/p>\n<h3>Ventajas de las campana de recirculaci\u00f3n<\/h3>\n<p><strong>M\u00e1xima eficiencia energ\u00e9tica.<\/strong> Los campanas de recirculaci\u00f3n s\u00f3n la opci\u00f3n m\u00e1s eficiente para renovar el aire de la cocina, evitando la p\u00e9rdida de calefacci\u00f3n en invierno y de aire acondicionado en verano.<\/p>\n<p><strong>Elimina el 96% de los olores, al\u00e9rgenos y sustancias contaminantes<\/strong> Adem\u00e1s de liberar el aire de grasas por medio de los filtros met\u00e1licos, se libera tambi\u00e9n de olores gracias al filtro de carb\u00f3n activo.<\/p>\n<p><strong>M\u00ednimo ruido un 14%.<\/strong> Mant\u00e9n una conversaci\u00f3n sin ninguna molestia en tu cocina durante su funcionamiento.<\/p>\n<p><strong>F\u00e1cil instalaci\u00f3n. <\/strong>la instalaci\u00f3n es m\u00e1s sencilla y flexible, al no depender de sistemas de conductos, ni de salidas de aire al exterior.<\/p>\n<p><a href=\"https:\/\/www.frecan.es\/campanas\/recirculacion\/\">Descubre todos los sistemas de recirculaci\u00f3n de Frecan<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Te damos la solucio\u0301n que dara\u0301 vida a muchas cocinas.<\/p>\n","protected":false},"author":2,"featured_media":2927,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[25,27],"tags":[],"class_list":{"0":"post-990","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-recirculacion-y-passivhaus","8":"category-campanas-extractoras"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Cocina sin salida de humos. Solucio\u0301n que dara\u0301 vida a muchas cocinas<\/title>\n<meta name=\"description\" content=\"Un problema en el que nos podemos encontrar es que no tengamos una salida de humos para poner una campana de extraccio\u0301n.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.frecan.es\/blog\/salida-de-humos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cocina sin salida de humos. Solucio\u0301n que dara\u0301 vida a muchas cocinas\" \/>\n<meta property=\"og:description\" content=\"Un problema en el que nos podemos encontrar es que no tengamos una salida de humos para poner una campana de extraccio\u0301n.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.frecan.es\/blog\/salida-de-humos\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog de Frecan\" \/>\n<meta property=\"article:published_time\" content=\"2020-02-19T12:42:14+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-22T11:35:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.frecan.es\/blog\/wp-content\/uploads\/2017\/02\/cocinas-sin-salida-de-humo-recirculacion-eficiente.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Frecan\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Frecan\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.frecan.es\/blog\/salida-de-humos\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.frecan.es\/blog\/salida-de-humos\/\"},\"author\":{\"name\":\"Frecan\",\"@id\":\"https:\/\/www.frecan.es\/blog\/#\/schema\/person\/eecbdddf4fc3d5ee61f34db3cfb262a4\"},\"headline\":\"Un problema en el que nos podemos encontrar es que no tengamos una salida de humos para poner una campana de extraccio\u0301n\",\"datePublished\":\"2020-02-19T12:42:14+00:00\",\"dateModified\":\"2023-02-22T11:35:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.frecan.es\/blog\/salida-de-humos\/\"},\"wordCount\":419,\"commentCount\":51,\"publisher\":{\"@id\":\"https:\/\/www.frecan.es\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.frecan.es\/blog\/salida-de-humos\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.frecan.es\/blog\/wp-content\/uploads\/2017\/02\/cocinas-sin-salida-de-humo-recirculacion-eficiente.jpg\",\"articleSection\":[\"Recirculaci\u00f3n sostenibilidad y Passivhaus\",\"Sistemas de extracci\u00f3n \/ campanas\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.frecan.es\/blog\/salida-de-humos\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.frecan.es\/blog\/salida-de-humos\/\",\"url\":\"https:\/\/www.frecan.es\/blog\/salida-de-humos\/\",\"name\":\"Cocina sin salida de humos. Solucio\u0301n que dara\u0301 vida a muchas cocinas\",\"isPartOf\":{\"@id\":\"https:\/\/www.frecan.es\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.frecan.es\/blog\/salida-de-humos\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.frecan.es\/blog\/salida-de-humos\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.frecan.es\/blog\/wp-content\/uploads\/2017\/02\/cocinas-sin-salida-de-humo-recirculacion-eficiente.jpg\",\"datePublished\":\"2020-02-19T12:42:14+00:00\",\"dateModified\":\"2023-02-22T11:35:30+00:00\",\"description\":\"Un problema en el que nos podemos encontrar es que no tengamos una salida de humos para poner una campana de extraccio\u0301n.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.frecan.es\/blog\/salida-de-humos\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.frecan.es\/blog\/salida-de-humos\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.frecan.es\/blog\/salida-de-humos\/#primaryimage\",\"url\":\"https:\/\/www.frecan.es\/blog\/wp-content\/uploads\/2017\/02\/cocinas-sin-salida-de-humo-recirculacion-eficiente.jpg\",\"contentUrl\":\"https:\/\/www.frecan.es\/blog\/wp-content\/uploads\/2017\/02\/cocinas-sin-salida-de-humo-recirculacion-eficiente.jpg\",\"width\":900,\"height\":900,\"caption\":\"Frecan, campana sin salida de humos. Recirculaci\u00f3n eficiente\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.frecan.es\/blog\/salida-de-humos\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.frecan.es\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Un problema en el que nos podemos encontrar es que no tengamos una salida de humos para poner una campana de extraccio\u0301n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.frecan.es\/blog\/#website\",\"url\":\"https:\/\/www.frecan.es\/blog\/\",\"name\":\"Blog de Frecan\",\"description\":\"Artesan\u00eda, tecnolog\u00eda y vanguardia en el coraz\u00f3n de tu cocina\",\"publisher\":{\"@id\":\"https:\/\/www.frecan.es\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.frecan.es\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.frecan.es\/blog\/#organization\",\"name\":\"Frecan\",\"url\":\"https:\/\/www.frecan.es\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.frecan.es\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.frecan.es\/blog\/wp-content\/uploads\/2016\/02\/logo-frecan.png\",\"contentUrl\":\"https:\/\/www.frecan.es\/blog\/wp-content\/uploads\/2016\/02\/logo-frecan.png\",\"width\":250,\"height\":27,\"caption\":\"Frecan\"},\"image\":{\"@id\":\"https:\/\/www.frecan.es\/blog\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.frecan.es\/blog\/#\/schema\/person\/eecbdddf4fc3d5ee61f34db3cfb262a4\",\"name\":\"Frecan\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.frecan.es\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/5f22fe11c8d7e915c3e67301f8a5068f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/5f22fe11c8d7e915c3e67301f8a5068f?s=96&d=mm&r=g\",\"caption\":\"Frecan\"},\"sameAs\":[\"http:\/\/www.frecan.es\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cocina sin salida de humos. Solucio\u0301n que dara\u0301 vida a muchas cocinas","description":"Un problema en el que nos podemos encontrar es que no tengamos una salida de humos para poner una campana de extraccio\u0301n.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.frecan.es\/blog\/salida-de-humos\/","og_locale":"es_ES","og_type":"article","og_title":"Cocina sin salida de humos. Solucio\u0301n que dara\u0301 vida a muchas cocinas","og_description":"Un problema en el que nos podemos encontrar es que no tengamos una salida de humos para poner una campana de extraccio\u0301n.","og_url":"https:\/\/www.frecan.es\/blog\/salida-de-humos\/","og_site_name":"Blog de Frecan","article_published_time":"2020-02-19T12:42:14+00:00","article_modified_time":"2023-02-22T11:35:30+00:00","og_image":[{"width":900,"height":900,"url":"https:\/\/www.frecan.es\/blog\/wp-content\/uploads\/2017\/02\/cocinas-sin-salida-de-humo-recirculacion-eficiente.jpg","type":"image\/jpeg"}],"author":"Frecan","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Frecan","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.frecan.es\/blog\/salida-de-humos\/#article","isPartOf":{"@id":"https:\/\/www.frecan.es\/blog\/salida-de-humos\/"},"author":{"name":"Frecan","@id":"https:\/\/www.frecan.es\/blog\/#\/schema\/person\/eecbdddf4fc3d5ee61f34db3cfb262a4"},"headline":"Un problema en el que nos podemos encontrar es que no tengamos una salida de humos para poner una campana de extraccio\u0301n","datePublished":"2020-02-19T12:42:14+00:00","dateModified":"2023-02-22T11:35:30+00:00","mainEntityOfPage":{"@id":"https:\/\/www.frecan.es\/blog\/salida-de-humos\/"},"wordCount":419,"commentCount":51,"publisher":{"@id":"https:\/\/www.frecan.es\/blog\/#organization"},"image":{"@id":"https:\/\/www.frecan.es\/blog\/salida-de-humos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.frecan.es\/blog\/wp-content\/uploads\/2017\/02\/cocinas-sin-salida-de-humo-recirculacion-eficiente.jpg","articleSection":["Recirculaci\u00f3n sostenibilidad y Passivhaus","Sistemas de extracci\u00f3n \/ campanas"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.frecan.es\/blog\/salida-de-humos\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.frecan.es\/blog\/salida-de-humos\/","url":"https:\/\/www.frecan.es\/blog\/salida-de-humos\/","name":"Cocina sin salida de humos. Solucio\u0301n que dara\u0301 vida a muchas cocinas","isPartOf":{"@id":"https:\/\/www.frecan.es\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.frecan.es\/blog\/salida-de-humos\/#primaryimage"},"image":{"@id":"https:\/\/www.frecan.es\/blog\/salida-de-humos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.frecan.es\/blog\/wp-content\/uploads\/2017\/02\/cocinas-sin-salida-de-humo-recirculacion-eficiente.jpg","datePublished":"2020-02-19T12:42:14+00:00","dateModified":"2023-02-22T11:35:30+00:00","description":"Un problema en el que nos podemos encontrar es que no tengamos una salida de humos para poner una campana de extraccio\u0301n.","breadcrumb":{"@id":"https:\/\/www.frecan.es\/blog\/salida-de-humos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.frecan.es\/blog\/salida-de-humos\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.frecan.es\/blog\/salida-de-humos\/#primaryimage","url":"https:\/\/www.frecan.es\/blog\/wp-content\/uploads\/2017\/02\/cocinas-sin-salida-de-humo-recirculacion-eficiente.jpg","contentUrl":"https:\/\/www.frecan.es\/blog\/wp-content\/uploads\/2017\/02\/cocinas-sin-salida-de-humo-recirculacion-eficiente.jpg","width":900,"height":900,"caption":"Frecan, campana sin salida de humos. Recirculaci\u00f3n eficiente"},{"@type":"BreadcrumbList","@id":"https:\/\/www.frecan.es\/blog\/salida-de-humos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.frecan.es\/blog\/"},{"@type":"ListItem","position":2,"name":"Un problema en el que nos podemos encontrar es que no tengamos una salida de humos para poner una campana de extraccio\u0301n"}]},{"@type":"WebSite","@id":"https:\/\/www.frecan.es\/blog\/#website","url":"https:\/\/www.frecan.es\/blog\/","name":"Blog de Frecan","description":"Artesan\u00eda, tecnolog\u00eda y vanguardia en el coraz\u00f3n de tu cocina","publisher":{"@id":"https:\/\/www.frecan.es\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.frecan.es\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.frecan.es\/blog\/#organization","name":"Frecan","url":"https:\/\/www.frecan.es\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.frecan.es\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.frecan.es\/blog\/wp-content\/uploads\/2016\/02\/logo-frecan.png","contentUrl":"https:\/\/www.frecan.es\/blog\/wp-content\/uploads\/2016\/02\/logo-frecan.png","width":250,"height":27,"caption":"Frecan"},"image":{"@id":"https:\/\/www.frecan.es\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.frecan.es\/blog\/#\/schema\/person\/eecbdddf4fc3d5ee61f34db3cfb262a4","name":"Frecan","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.frecan.es\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/5f22fe11c8d7e915c3e67301f8a5068f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5f22fe11c8d7e915c3e67301f8a5068f?s=96&d=mm&r=g","caption":"Frecan"},"sameAs":["http:\/\/www.frecan.es\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.frecan.es\/blog\/wp-json\/wp\/v2\/posts\/990","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.frecan.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.frecan.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.frecan.es\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.frecan.es\/blog\/wp-json\/wp\/v2\/comments?post=990"}],"version-history":[{"count":20,"href":"https:\/\/www.frecan.es\/blog\/wp-json\/wp\/v2\/posts\/990\/revisions"}],"predecessor-version":[{"id":8273,"href":"https:\/\/www.frecan.es\/blog\/wp-json\/wp\/v2\/posts\/990\/revisions\/8273"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.frecan.es\/blog\/wp-json\/wp\/v2\/media\/2927"}],"wp:attachment":[{"href":"https:\/\/www.frecan.es\/blog\/wp-json\/wp\/v2\/media?parent=990"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.frecan.es\/blog\/wp-json\/wp\/v2\/categories?post=990"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.frecan.es\/blog\/wp-json\/wp\/v2\/tags?post=990"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}