{"id":8646,"date":"2023-04-26T10:30:13","date_gmt":"2023-04-26T10:30:13","guid":{"rendered":"https:\/\/www.frecan.es\/blog\/?p=8646"},"modified":"2023-04-27T09:53:20","modified_gmt":"2023-04-27T09:53:20","slug":"energia-solar","status":"publish","type":"post","link":"https:\/\/www.frecan.es\/blog\/energia-solar\/","title":{"rendered":"Energ\u00eda solar como alternativa sostenible"},"content":{"rendered":"<h2 style=\"color: #949494; font-size: 24px; line-height: 26px; margin-top: -20px;\">En Frecan tenemos una visi\u00f3n clara: ofrecer a nuestros clientes un servicio de calidad y eficiencia, basado en la innovaci\u00f3n y la mejora continua.<\/h2>\n<p><!--more--><\/p>\n<h2 style=\"color: #949494; font-size: 24px; line-height: 26px;\">Pero tambi\u00e9n tenemos una misi\u00f3n: cuidar el medio ambiente y el futuro del planeta, que es el hogar de todos.<\/h2>\n<p data-wp-editing=\"1\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-8647 size-full\" src=\"https:\/\/www.frecan.es\/blog\/wp-content\/uploads\/2023\/04\/pexels-bhupendra-singh-760680-scaled.jpg\" alt=\"energ\u00eda solar - sol\" width=\"2560\" height=\"1834\" srcset=\"https:\/\/www.frecan.es\/blog\/wp-content\/uploads\/2023\/04\/pexels-bhupendra-singh-760680-scaled.jpg 2560w, https:\/\/www.frecan.es\/blog\/wp-content\/uploads\/2023\/04\/pexels-bhupendra-singh-760680-300x215.jpg 300w, https:\/\/www.frecan.es\/blog\/wp-content\/uploads\/2023\/04\/pexels-bhupendra-singh-760680-1024x734.jpg 1024w, https:\/\/www.frecan.es\/blog\/wp-content\/uploads\/2023\/04\/pexels-bhupendra-singh-760680-768x550.jpg 768w, https:\/\/www.frecan.es\/blog\/wp-content\/uploads\/2023\/04\/pexels-bhupendra-singh-760680-1536x1101.jpg 1536w, https:\/\/www.frecan.es\/blog\/wp-content\/uploads\/2023\/04\/pexels-bhupendra-singh-760680-2048x1468.jpg 2048w, https:\/\/www.frecan.es\/blog\/wp-content\/uploads\/2023\/04\/pexels-bhupendra-singh-760680-800x573.jpg 800w, https:\/\/www.frecan.es\/blog\/wp-content\/uploads\/2023\/04\/pexels-bhupendra-singh-760680-1280x917.jpg 1280w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/p>\n<p><strong>Por eso, hemos decidido apostar por la energ\u00eda solar como fuente de electricidad para nuestras instalaciones.<\/strong><br \/>\nLa energ\u00eda solar es una <strong>energ\u00eda limpia, renovable e inagotabl<\/strong>e, que aprovecha la luz y el calor del sol para generar electricidad de forma sostenible.<\/p>\n<p>Al usar esta energ\u00eda, reducimos nuestra dependencia de los combustibles f\u00f3siles, que son finitos y que emiten gases de efecto invernadero y otros residuos t\u00f3xicos que contaminan el aire, el agua y la tierra. Adem\u00e1s, nos permite ahorrar en nuestra factura de electricidad, ya que <strong>generamos nuestra propia energ\u00eda<\/strong> y solo recurrimos a la red cuando es necesario.<\/p>\n<p>Con esta medida, queremos demostrar nuestro compromiso con el <strong>desarrollo sostenible y la responsabilidad social<\/strong>, as\u00ed como con la satisfacci\u00f3n de nuestros clientes. Estamos orgullosos de formar parte de la revoluci\u00f3n energ\u00e9tica del siglo XXI y de contribuir a un mundo m\u00e1s verde y mejor para todos.<\/p>\n<p><a href=\"https:\/\/www.frecan.es\/\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"1723\" height=\"1080\" class=\"aligncenter wp-image-8650 size-full\" src=\"https:\/\/www.frecan.es\/blog\/wp-content\/uploads\/2023\/04\/PlacasSolares-Frecan-1.jpg\" class=\"light\" srcset=\"https:\/\/www.frecan.es\/blog\/wp-content\/uploads\/2023\/04\/PlacasSolares-Frecan-1.jpg 1723w, https:\/\/www.frecan.es\/blog\/wp-content\/uploads\/2023\/04\/PlacasSolares-Frecan-1-300x188.jpg 300w, https:\/\/www.frecan.es\/blog\/wp-content\/uploads\/2023\/04\/PlacasSolares-Frecan-1-1024x642.jpg 1024w, https:\/\/www.frecan.es\/blog\/wp-content\/uploads\/2023\/04\/PlacasSolares-Frecan-1-768x481.jpg 768w, https:\/\/www.frecan.es\/blog\/wp-content\/uploads\/2023\/04\/PlacasSolares-Frecan-1-1536x963.jpg 1536w, https:\/\/www.frecan.es\/blog\/wp-content\/uploads\/2023\/04\/PlacasSolares-Frecan-1-800x501.jpg 800w, https:\/\/www.frecan.es\/blog\/wp-content\/uploads\/2023\/04\/PlacasSolares-Frecan-1-1280x802.jpg 1280w\" sizes=\"auto, (max-width: 1723px) 100vw, 1723px\" \/><\/a><\/p>\n<p>Pero esta no es la \u00fanica acci\u00f3n que hemos realizado para <strong>cuidar el medio ambiente<\/strong>. Tambi\u00e9n hemos implementado medidas de eficiencia energ\u00e9tica en nuestras oficinas, como el uso de <strong>iluminaci\u00f3n LED<\/strong>, el aprovechamiento de la <strong>luz natural<\/strong> y el <strong>control de la temperatura<\/strong>. Asimismo, hemos reducido nuestro consumo de papel y pl\u00e1stico, y seguimos fomentando el reciclaje y la reutilizaci\u00f3n de materiales. Todo ello sin renunciar a la calidad de nuestros productos y servicios, que son el resultado de nuestro trabajo profesional y dedicado.<\/p>\n<div class=\"columns medium-4\" style=\"padding: 0 25px 20px 0; font-size: 13px;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-8681 size-medium\" src=\"https:\/\/www.frecan.es\/blog\/wp-content\/uploads\/2023\/04\/CO2-300x278.png\" alt=\"energ\u00eda - CO2\" width=\"300\" height=\"278\" srcset=\"https:\/\/www.frecan.es\/blog\/wp-content\/uploads\/2023\/04\/CO2-300x278.png 300w, https:\/\/www.frecan.es\/blog\/wp-content\/uploads\/2023\/04\/CO2.png 677w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><br \/>\n*97.921 kg\/a\u00f1o emisiones de CO2 evitadas gracias a la instalaci\u00f3n de autoconsumo.<\/div>\n<div class=\"columns medium-4\" style=\"padding: 0 25px 20px 0; font-size: 13px;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-8678 size-medium\" src=\"https:\/\/www.frecan.es\/blog\/wp-content\/uploads\/2023\/04\/ARBOLES-300x278.png\" alt=\"energ\u00eda - \u00e1rboles\" width=\"300\" height=\"278\" srcset=\"https:\/\/www.frecan.es\/blog\/wp-content\/uploads\/2023\/04\/ARBOLES-300x278.png 300w, https:\/\/www.frecan.es\/blog\/wp-content\/uploads\/2023\/04\/ARBOLES.png 677w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><br \/>\n*3.917 \u00e1rboles necesarios para absorber las toneladas de CO2 ahorradas.<\/div>\n<div class=\"columns medium-4\" style=\"padding: 0 25px 20px 0; font-size: 13px;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-8684 size-medium\" src=\"https:\/\/www.frecan.es\/blog\/wp-content\/uploads\/2023\/04\/KMS-300x278.png\" alt=\"Energ\u00eda - KMS\" width=\"300\" height=\"278\" srcset=\"https:\/\/www.frecan.es\/blog\/wp-content\/uploads\/2023\/04\/KMS-300x278.png 300w, https:\/\/www.frecan.es\/blog\/wp-content\/uploads\/2023\/04\/KMS.png 677w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\n<\/div>\n<p>*1.125.269 kms los que deber\u00eda recorrer un coche para emitir CO2 que ahorramos en un a\u00f1o.<\/p><\/div>\n<p>Adem\u00e1s, en Frecan apostamos por la descentralizaci\u00f3n y la <strong>econom\u00eda circular<\/strong>, trabajando con fabricantes de componentes locales que nos proveen de materiales de primera calidad y que reducen la huella ecol\u00f3gica del transporte. En Frecan creemos que es posible combinar el \u00e9xito empresarial con el respeto al medio ambiente.<\/p>\n<p><em>Y t\u00fa, \u00bfte unes a la causa?<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En Frecan tenemos una visi\u00f3n clara: ofrecer a nuestros clientes un servicio de calidad y eficiencia, basado en la innovaci\u00f3n y la mejora continua.<\/p>\n","protected":false},"author":8,"featured_media":8647,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[25,9],"tags":[],"class_list":{"0":"post-8646","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-recirculacion-y-passivhaus","8":"category-tecnologia"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Energ\u00eda solar como alternativa sostenible - Blog de Frecan<\/title>\n<meta name=\"description\" content=\"Comprometidos con el desarrollo sostenible y la responsabilidad social; apostamos por la energ\u00eda solar como fuente de electricidad.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.frecan.es\/blog\/energia-solar\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Energ\u00eda solar como alternativa sostenible - Blog de Frecan\" \/>\n<meta property=\"og:description\" content=\"Comprometidos con el desarrollo sostenible y la responsabilidad social; apostamos por la energ\u00eda solar como fuente de electricidad.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.frecan.es\/blog\/energia-solar\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog de Frecan\" \/>\n<meta property=\"article:published_time\" content=\"2023-04-26T10:30:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-04-27T09:53:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.frecan.es\/blog\/wp-content\/uploads\/2023\/04\/pexels-bhupendra-singh-760680-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1834\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Tha\u00efs Alcal\u00e1\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Tha\u00efs Alcal\u00e1\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.frecan.es\/blog\/energia-solar\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.frecan.es\/blog\/energia-solar\/\"},\"author\":{\"name\":\"Tha\u00efs Alcal\u00e1\",\"@id\":\"https:\/\/www.frecan.es\/blog\/#\/schema\/person\/807ea11d2c3f88890ae67a52637b8b3c\"},\"headline\":\"Energ\u00eda solar como alternativa sostenible\",\"datePublished\":\"2023-04-26T10:30:13+00:00\",\"dateModified\":\"2023-04-27T09:53:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.frecan.es\/blog\/energia-solar\/\"},\"wordCount\":402,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.frecan.es\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.frecan.es\/blog\/energia-solar\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.frecan.es\/blog\/wp-content\/uploads\/2023\/04\/pexels-bhupendra-singh-760680-scaled.jpg\",\"articleSection\":[\"Recirculaci\u00f3n sostenibilidad y Passivhaus\",\"Tecnolog\u00eda\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.frecan.es\/blog\/energia-solar\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.frecan.es\/blog\/energia-solar\/\",\"url\":\"https:\/\/www.frecan.es\/blog\/energia-solar\/\",\"name\":\"Energ\u00eda solar como alternativa sostenible - Blog de Frecan\",\"isPartOf\":{\"@id\":\"https:\/\/www.frecan.es\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.frecan.es\/blog\/energia-solar\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.frecan.es\/blog\/energia-solar\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.frecan.es\/blog\/wp-content\/uploads\/2023\/04\/pexels-bhupendra-singh-760680-scaled.jpg\",\"datePublished\":\"2023-04-26T10:30:13+00:00\",\"dateModified\":\"2023-04-27T09:53:20+00:00\",\"description\":\"Comprometidos con el desarrollo sostenible y la responsabilidad social; apostamos por la energ\u00eda solar como fuente de electricidad.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.frecan.es\/blog\/energia-solar\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.frecan.es\/blog\/energia-solar\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.frecan.es\/blog\/energia-solar\/#primaryimage\",\"url\":\"https:\/\/www.frecan.es\/blog\/wp-content\/uploads\/2023\/04\/pexels-bhupendra-singh-760680-scaled.jpg\",\"contentUrl\":\"https:\/\/www.frecan.es\/blog\/wp-content\/uploads\/2023\/04\/pexels-bhupendra-singh-760680-scaled.jpg\",\"width\":2560,\"height\":1834,\"caption\":\"energ\u00eda solar - sol\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.frecan.es\/blog\/energia-solar\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.frecan.es\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Energ\u00eda solar como alternativa sostenible\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.frecan.es\/blog\/#website\",\"url\":\"https:\/\/www.frecan.es\/blog\/\",\"name\":\"Blog de Frecan\",\"description\":\"Artesan\u00eda, tecnolog\u00eda y vanguardia en el coraz\u00f3n de tu cocina\",\"publisher\":{\"@id\":\"https:\/\/www.frecan.es\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.frecan.es\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.frecan.es\/blog\/#organization\",\"name\":\"Frecan\",\"url\":\"https:\/\/www.frecan.es\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.frecan.es\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.frecan.es\/blog\/wp-content\/uploads\/2016\/02\/logo-frecan.png\",\"contentUrl\":\"https:\/\/www.frecan.es\/blog\/wp-content\/uploads\/2016\/02\/logo-frecan.png\",\"width\":250,\"height\":27,\"caption\":\"Frecan\"},\"image\":{\"@id\":\"https:\/\/www.frecan.es\/blog\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.frecan.es\/blog\/#\/schema\/person\/807ea11d2c3f88890ae67a52637b8b3c\",\"name\":\"Tha\u00efs Alcal\u00e1\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.frecan.es\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/ad063cd811075f52af0714b5e973cd08?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/ad063cd811075f52af0714b5e973cd08?s=96&d=mm&r=g\",\"caption\":\"Tha\u00efs Alcal\u00e1\"},\"sameAs\":[\"http:\/\/www.frecan.es\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Energ\u00eda solar como alternativa sostenible - Blog de Frecan","description":"Comprometidos con el desarrollo sostenible y la responsabilidad social; apostamos por la energ\u00eda solar como fuente de electricidad.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.frecan.es\/blog\/energia-solar\/","og_locale":"es_ES","og_type":"article","og_title":"Energ\u00eda solar como alternativa sostenible - Blog de Frecan","og_description":"Comprometidos con el desarrollo sostenible y la responsabilidad social; apostamos por la energ\u00eda solar como fuente de electricidad.","og_url":"https:\/\/www.frecan.es\/blog\/energia-solar\/","og_site_name":"Blog de Frecan","article_published_time":"2023-04-26T10:30:13+00:00","article_modified_time":"2023-04-27T09:53:20+00:00","og_image":[{"width":2560,"height":1834,"url":"https:\/\/www.frecan.es\/blog\/wp-content\/uploads\/2023\/04\/pexels-bhupendra-singh-760680-scaled.jpg","type":"image\/jpeg"}],"author":"Tha\u00efs Alcal\u00e1","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Tha\u00efs Alcal\u00e1","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.frecan.es\/blog\/energia-solar\/#article","isPartOf":{"@id":"https:\/\/www.frecan.es\/blog\/energia-solar\/"},"author":{"name":"Tha\u00efs Alcal\u00e1","@id":"https:\/\/www.frecan.es\/blog\/#\/schema\/person\/807ea11d2c3f88890ae67a52637b8b3c"},"headline":"Energ\u00eda solar como alternativa sostenible","datePublished":"2023-04-26T10:30:13+00:00","dateModified":"2023-04-27T09:53:20+00:00","mainEntityOfPage":{"@id":"https:\/\/www.frecan.es\/blog\/energia-solar\/"},"wordCount":402,"commentCount":0,"publisher":{"@id":"https:\/\/www.frecan.es\/blog\/#organization"},"image":{"@id":"https:\/\/www.frecan.es\/blog\/energia-solar\/#primaryimage"},"thumbnailUrl":"https:\/\/www.frecan.es\/blog\/wp-content\/uploads\/2023\/04\/pexels-bhupendra-singh-760680-scaled.jpg","articleSection":["Recirculaci\u00f3n sostenibilidad y Passivhaus","Tecnolog\u00eda"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.frecan.es\/blog\/energia-solar\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.frecan.es\/blog\/energia-solar\/","url":"https:\/\/www.frecan.es\/blog\/energia-solar\/","name":"Energ\u00eda solar como alternativa sostenible - Blog de Frecan","isPartOf":{"@id":"https:\/\/www.frecan.es\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.frecan.es\/blog\/energia-solar\/#primaryimage"},"image":{"@id":"https:\/\/www.frecan.es\/blog\/energia-solar\/#primaryimage"},"thumbnailUrl":"https:\/\/www.frecan.es\/blog\/wp-content\/uploads\/2023\/04\/pexels-bhupendra-singh-760680-scaled.jpg","datePublished":"2023-04-26T10:30:13+00:00","dateModified":"2023-04-27T09:53:20+00:00","description":"Comprometidos con el desarrollo sostenible y la responsabilidad social; apostamos por la energ\u00eda solar como fuente de electricidad.","breadcrumb":{"@id":"https:\/\/www.frecan.es\/blog\/energia-solar\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.frecan.es\/blog\/energia-solar\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.frecan.es\/blog\/energia-solar\/#primaryimage","url":"https:\/\/www.frecan.es\/blog\/wp-content\/uploads\/2023\/04\/pexels-bhupendra-singh-760680-scaled.jpg","contentUrl":"https:\/\/www.frecan.es\/blog\/wp-content\/uploads\/2023\/04\/pexels-bhupendra-singh-760680-scaled.jpg","width":2560,"height":1834,"caption":"energ\u00eda solar - sol"},{"@type":"BreadcrumbList","@id":"https:\/\/www.frecan.es\/blog\/energia-solar\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.frecan.es\/blog\/"},{"@type":"ListItem","position":2,"name":"Energ\u00eda solar como alternativa sostenible"}]},{"@type":"WebSite","@id":"https:\/\/www.frecan.es\/blog\/#website","url":"https:\/\/www.frecan.es\/blog\/","name":"Blog de Frecan","description":"Artesan\u00eda, tecnolog\u00eda y vanguardia en el coraz\u00f3n de tu cocina","publisher":{"@id":"https:\/\/www.frecan.es\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.frecan.es\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.frecan.es\/blog\/#organization","name":"Frecan","url":"https:\/\/www.frecan.es\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.frecan.es\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.frecan.es\/blog\/wp-content\/uploads\/2016\/02\/logo-frecan.png","contentUrl":"https:\/\/www.frecan.es\/blog\/wp-content\/uploads\/2016\/02\/logo-frecan.png","width":250,"height":27,"caption":"Frecan"},"image":{"@id":"https:\/\/www.frecan.es\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.frecan.es\/blog\/#\/schema\/person\/807ea11d2c3f88890ae67a52637b8b3c","name":"Tha\u00efs Alcal\u00e1","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.frecan.es\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/ad063cd811075f52af0714b5e973cd08?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ad063cd811075f52af0714b5e973cd08?s=96&d=mm&r=g","caption":"Tha\u00efs Alcal\u00e1"},"sameAs":["http:\/\/www.frecan.es"]}]}},"_links":{"self":[{"href":"https:\/\/www.frecan.es\/blog\/wp-json\/wp\/v2\/posts\/8646","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.frecan.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.frecan.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.frecan.es\/blog\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.frecan.es\/blog\/wp-json\/wp\/v2\/comments?post=8646"}],"version-history":[{"count":12,"href":"https:\/\/www.frecan.es\/blog\/wp-json\/wp\/v2\/posts\/8646\/revisions"}],"predecessor-version":[{"id":8689,"href":"https:\/\/www.frecan.es\/blog\/wp-json\/wp\/v2\/posts\/8646\/revisions\/8689"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.frecan.es\/blog\/wp-json\/wp\/v2\/media\/8647"}],"wp:attachment":[{"href":"https:\/\/www.frecan.es\/blog\/wp-json\/wp\/v2\/media?parent=8646"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.frecan.es\/blog\/wp-json\/wp\/v2\/categories?post=8646"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.frecan.es\/blog\/wp-json\/wp\/v2\/tags?post=8646"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}