{"id":7919,"date":"2022-11-29T20:51:28","date_gmt":"2022-11-29T20:51:28","guid":{"rendered":"https:\/\/www.frecan.es\/blog\/flagship-store-paris-de-florim\/"},"modified":"2022-11-29T20:51:28","modified_gmt":"2022-11-29T20:51:28","slug":"flagship-store-paris-de-florim","status":"publish","type":"post","link":"https:\/\/www.frecan.es\/blog\/en\/flagship-store-paris-de-florim\/","title":{"rendered":"Experimenta posibilidades ilimitadas, de la m\u00e1s alta calidad, para la planificaci\u00f3n de su hogar en el coraz\u00f3n de Par\u00eds."},"content":{"rendered":"<h2 style=\"color: #949494; font-size: 24px; line-height: 26px; margin-top: -20px;\">Redise\u00f1ar o dise\u00f1ar tu casa es uno de los proyectos m\u00e1s grandes e importantes. Es emocionante, pero a la vez tambi\u00e9n puede ser desalentador si no sabes c\u00f3mo empezar.<!--more--><\/h2>\n<p>Si est\u00e1 interesado en visitar una sala de exposici\u00f3n totalmente exclusiva en el coraz\u00f3n de Par\u00eds, d\u00f3nde se encuentran los lugares simb\u00f3licos, como el museo del Louvre, la plaza de las Victorias y la plaza Vend\u00f4me, aseg\u00farese de visitar la <a href=\"https:\/\/www.florim.com\/es\/empresa\/showroom\/flagship-store-paris\/\" target=\"_blank\" rel=\"noopener\">Flagship Store Paris de Florim<\/a>, un espacio referencial del hogar.<\/p>\n<h3>Siente la m\u00e1s alta calidad y obt\u00e9n asesoramiento gratuito de grandes expertos<\/h3>\n<p>Realmente no hay mejor manera de apreciar las cualidades llamativas de todas las cocinas que poder verlas y tocarlas en una sala de exposici\u00f3n de 650m2, dividida en plantas. Un espacio multifuncional dedicado a las encimeras porcel\u00e1nicas de m\u00e1s alta calidad de Florim combinado con armarios de cocina de <a href=\"https:\/\/www.modulnova.com\/es\/\" target=\"_blank\" rel=\"noopener\">MODULNOVA<\/a>, hasta electrodom\u00e9sticos y accesorios de cocina de alta gama.<\/p>\n\n\t\t<style type=\"text\/css\">\n\t\t\t#gallery-1 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 33%;\n\t\t\t}\n\t\t\t#gallery-1 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-1' class='gallery galleryid-7919 gallery-columns-3 gallery-size-large'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.frecan.es\/blog\/en\/flagship-store-paris-de-florim\/florim-paris-campana-superficie-flow-5-2\/'><img loading=\"lazy\" decoding=\"async\" width=\"819\" height=\"1024\" src=\"https:\/\/www.frecan.es\/blog\/wp-content\/uploads\/2022\/11\/florim-paris-campana-superficie-flow-5-819x1024.jpg\" class=\"attachment-large size-large\" alt=\"Flagship Store Paris de Florim - Campana superficie\" srcset=\"https:\/\/www.frecan.es\/blog\/wp-content\/uploads\/2022\/11\/florim-paris-campana-superficie-flow-5-819x1024.jpg 819w, https:\/\/www.frecan.es\/blog\/wp-content\/uploads\/2022\/11\/florim-paris-campana-superficie-flow-5-240x300.jpg 240w, https:\/\/www.frecan.es\/blog\/wp-content\/uploads\/2022\/11\/florim-paris-campana-superficie-flow-5-768x960.jpg 768w, https:\/\/www.frecan.es\/blog\/wp-content\/uploads\/2022\/11\/florim-paris-campana-superficie-flow-5-1229x1536.jpg 1229w, https:\/\/www.frecan.es\/blog\/wp-content\/uploads\/2022\/11\/florim-paris-campana-superficie-flow-5-800x1000.jpg 800w, https:\/\/www.frecan.es\/blog\/wp-content\/uploads\/2022\/11\/florim-paris-campana-superficie-flow-5-1280x1600.jpg 1280w, https:\/\/www.frecan.es\/blog\/wp-content\/uploads\/2022\/11\/florim-paris-campana-superficie-flow-5.jpg 1512w\" sizes=\"auto, (max-width: 819px) 100vw, 819px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.frecan.es\/blog\/en\/flagship-store-paris-de-florim\/florim-paris-campana-superficie-flow-4-2\/'><img loading=\"lazy\" decoding=\"async\" width=\"819\" height=\"1024\" src=\"https:\/\/www.frecan.es\/blog\/wp-content\/uploads\/2022\/11\/florim-paris-campana-superficie-flow-4-819x1024.jpg\" class=\"attachment-large size-large\" alt=\"Flagship Store Paris de Florim - Campana superficie\" srcset=\"https:\/\/www.frecan.es\/blog\/wp-content\/uploads\/2022\/11\/florim-paris-campana-superficie-flow-4-819x1024.jpg 819w, https:\/\/www.frecan.es\/blog\/wp-content\/uploads\/2022\/11\/florim-paris-campana-superficie-flow-4-240x300.jpg 240w, https:\/\/www.frecan.es\/blog\/wp-content\/uploads\/2022\/11\/florim-paris-campana-superficie-flow-4-768x960.jpg 768w, https:\/\/www.frecan.es\/blog\/wp-content\/uploads\/2022\/11\/florim-paris-campana-superficie-flow-4-800x1000.jpg 800w, https:\/\/www.frecan.es\/blog\/wp-content\/uploads\/2022\/11\/florim-paris-campana-superficie-flow-4.jpg 1134w\" sizes=\"auto, (max-width: 819px) 100vw, 819px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.frecan.es\/blog\/en\/flagship-store-paris-de-florim\/florim-paris-campana-superficie-flow-1-2\/'><img loading=\"lazy\" decoding=\"async\" width=\"819\" height=\"1024\" src=\"https:\/\/www.frecan.es\/blog\/wp-content\/uploads\/2022\/11\/florim-paris-campana-superficie-flow-1-819x1024.jpg\" class=\"attachment-large size-large\" alt=\"Flagship Store Paris de Florim - Campana superficie\" srcset=\"https:\/\/www.frecan.es\/blog\/wp-content\/uploads\/2022\/11\/florim-paris-campana-superficie-flow-1-819x1024.jpg 819w, https:\/\/www.frecan.es\/blog\/wp-content\/uploads\/2022\/11\/florim-paris-campana-superficie-flow-1-240x300.jpg 240w, https:\/\/www.frecan.es\/blog\/wp-content\/uploads\/2022\/11\/florim-paris-campana-superficie-flow-1-768x960.jpg 768w, https:\/\/www.frecan.es\/blog\/wp-content\/uploads\/2022\/11\/florim-paris-campana-superficie-flow-1-800x1000.jpg 800w, https:\/\/www.frecan.es\/blog\/wp-content\/uploads\/2022\/11\/florim-paris-campana-superficie-flow-1.jpg 1134w\" sizes=\"auto, (max-width: 819px) 100vw, 819px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.frecan.es\/blog\/en\/flagship-store-paris-de-florim\/florim-paris-campana-superficie-flow-0-2\/'><img loading=\"lazy\" decoding=\"async\" width=\"819\" height=\"1024\" src=\"https:\/\/www.frecan.es\/blog\/wp-content\/uploads\/2022\/11\/florim-paris-campana-superficie-flow-0-819x1024.jpg\" class=\"attachment-large size-large\" alt=\"Flagship Store Paris de Florim - Campana superficie\" srcset=\"https:\/\/www.frecan.es\/blog\/wp-content\/uploads\/2022\/11\/florim-paris-campana-superficie-flow-0-819x1024.jpg 819w, https:\/\/www.frecan.es\/blog\/wp-content\/uploads\/2022\/11\/florim-paris-campana-superficie-flow-0-240x300.jpg 240w, https:\/\/www.frecan.es\/blog\/wp-content\/uploads\/2022\/11\/florim-paris-campana-superficie-flow-0-768x960.jpg 768w, https:\/\/www.frecan.es\/blog\/wp-content\/uploads\/2022\/11\/florim-paris-campana-superficie-flow-0-800x1000.jpg 800w, https:\/\/www.frecan.es\/blog\/wp-content\/uploads\/2022\/11\/florim-paris-campana-superficie-flow-0.jpg 1134w\" sizes=\"auto, (max-width: 819px) 100vw, 819px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.frecan.es\/blog\/en\/flagship-store-paris-de-florim\/florim-paris-campana-superficie-flow-6\/'><img loading=\"lazy\" decoding=\"async\" width=\"819\" height=\"1024\" src=\"https:\/\/www.frecan.es\/blog\/wp-content\/uploads\/2022\/11\/florim-paris-campana-superficie-flow-819x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/www.frecan.es\/blog\/wp-content\/uploads\/2022\/11\/florim-paris-campana-superficie-flow-819x1024.jpg 819w, https:\/\/www.frecan.es\/blog\/wp-content\/uploads\/2022\/11\/florim-paris-campana-superficie-flow-240x300.jpg 240w, https:\/\/www.frecan.es\/blog\/wp-content\/uploads\/2022\/11\/florim-paris-campana-superficie-flow-768x960.jpg 768w, https:\/\/www.frecan.es\/blog\/wp-content\/uploads\/2022\/11\/florim-paris-campana-superficie-flow-800x1000.jpg 800w, https:\/\/www.frecan.es\/blog\/wp-content\/uploads\/2022\/11\/florim-paris-campana-superficie-flow.jpg 1134w\" sizes=\"auto, (max-width: 819px) 100vw, 819px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.frecan.es\/blog\/en\/flagship-store-paris-de-florim\/florim-paris-campana-superficie-flow-2-2\/'><img loading=\"lazy\" decoding=\"async\" width=\"819\" height=\"1024\" src=\"https:\/\/www.frecan.es\/blog\/wp-content\/uploads\/2022\/11\/florim-paris-campana-superficie-flow-2-819x1024.jpg\" class=\"attachment-large size-large\" alt=\"Flagship Store Paris de Florim - Campana superficie\" srcset=\"https:\/\/www.frecan.es\/blog\/wp-content\/uploads\/2022\/11\/florim-paris-campana-superficie-flow-2-819x1024.jpg 819w, https:\/\/www.frecan.es\/blog\/wp-content\/uploads\/2022\/11\/florim-paris-campana-superficie-flow-2-240x300.jpg 240w, https:\/\/www.frecan.es\/blog\/wp-content\/uploads\/2022\/11\/florim-paris-campana-superficie-flow-2-768x960.jpg 768w, https:\/\/www.frecan.es\/blog\/wp-content\/uploads\/2022\/11\/florim-paris-campana-superficie-flow-2-800x1000.jpg 800w, https:\/\/www.frecan.es\/blog\/wp-content\/uploads\/2022\/11\/florim-paris-campana-superficie-flow-2.jpg 1134w\" sizes=\"auto, (max-width: 819px) 100vw, 819px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/>\n\t\t<\/div>\n\n<p>Visitarlos te har\u00e1 sentir la calidad y la artesan\u00eda de su cocina. Desde lo \u00faltimo en dise\u00f1o de cocinas modernas hasta la calidez tradicional. \u00a1Tienen una cocina que se adapta a tu estilo!<\/p>\n<p>Adem\u00e1s, est\u00e1n a su disposici\u00f3n para responder a cualquiera de sus preguntas y guiarlo mientras crea la cocina de sus sue\u00f1os.<\/p>\n<h3>Flow 54, el dise\u00f1o y la tecnolog\u00eda que no se ve<\/h3>\n<p>S\u00f3lo al entrar en el <a href=\"https:\/\/www.florim.com\/es\/empresa\/showroom\/flagship-store-paris\/\" target=\"_blank\" rel=\"noopener\">Flagship Store Paris de Florim<\/a>, nos encontramos un gran recibidor con nuestra joya del cat\u00e1logo, <a href=\"https:\/\/www.frecan.es\/blog\/en\/flow-5-let-it-all-flow\/\" target=\"_blank\" rel=\"noopener\">la campana de superficie Flow 54<\/a> .Instalada discretamente entre 4 zonas de cocci\u00f3n, su discreto panel de vidrio se retrae para que el humo, los olores y el vapor de la cocci\u00f3n desaparezcan literalmente con una eficiencia incomparable.<\/p>\n<p>La semana pasada tuvimos la oportunidad de hacer un training, para que no exista un margen de error en su instalaci\u00f3n, ense\u00f1ar todas sus ventajas y posibilidades y hacerla protagonista del espacio.<\/p>\n<p>\u00bfTe han entrado ganas irrefrenables de entrar al<a href=\"https:\/\/www.florim.com\/es\/empresa\/showroom\/flagship-store-paris\/\"> Flagship Store Paris de Florim<\/a>? \u00a1A nosotros, de quedarnos a vivir ah\u00ed!<\/p>\n<h4>Descubre m\u00e1s sobre la Flow<\/h4>\n<blockquote class=\"wp-embedded-content\" data-secret=\"prUnxKXNba\"><p><a href=\"https:\/\/www.frecan.es\/blog\/en\/flow-5-let-it-all-flow\/\">Deja que todo fluya<\/a><\/p><\/blockquote>\n<p><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"&#8220;Deja que todo fluya&#8221; &#8212; Blog de Frecan\" src=\"https:\/\/www.frecan.es\/blog\/en\/flow-5-let-it-all-flow\/embed\/#?secret=Gk7kRERujn#?secret=prUnxKXNba\" data-secret=\"prUnxKXNba\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n<blockquote class=\"wp-embedded-content\" data-secret=\"PIuX34zf9x\"><p><a href=\"https:\/\/www.frecan.es\/blog\/instalar-la-campana-de-superficie\/\">\u00bfC\u00f3mo instalar la campana de superficie Flow 5?<\/a><\/p><\/blockquote>\n<p><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"&#8220;\u00bfC\u00f3mo instalar la campana de superficie Flow 5?&#8221; &#8212; Blog de Frecan\" src=\"https:\/\/www.frecan.es\/blog\/instalar-la-campana-de-superficie\/embed\/#?secret=sOkqKJpHjt#?secret=PIuX34zf9x\" data-secret=\"PIuX34zf9x\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Redise\u00f1ar o dise\u00f1ar tu casa es uno de los proyectos m\u00e1s grandes e importantes. Es emocionante, pero a la vez tambi\u00e9n puede ser desalentador si no sabes c\u00f3mo empezar.<\/p>\n","protected":false},"author":2,"featured_media":7911,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[43,36],"tags":[],"class_list":{"0":"post-7919","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-dealers","8":"category-design-kitchens"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Experimenta posibilidades ilimitadas, de la m\u00e1s alta calidad, para la planificaci\u00f3n de su hogar en el coraz\u00f3n de Par\u00eds. - Blog de Frecan<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.frecan.es\/blog\/en\/flagship-store-paris-de-florim\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Experimenta posibilidades ilimitadas, de la m\u00e1s alta calidad, para la planificaci\u00f3n de su hogar en el coraz\u00f3n de Par\u00eds. - Blog de Frecan\" \/>\n<meta property=\"og:description\" content=\"Redise\u00f1ar o dise\u00f1ar tu casa es uno de los proyectos m\u00e1s grandes e importantes. Es emocionante, pero a la vez tambi\u00e9n puede ser desalentador si no sabes c\u00f3mo empezar.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.frecan.es\/blog\/en\/flagship-store-paris-de-florim\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog de Frecan\" \/>\n<meta property=\"article:published_time\" content=\"2022-11-29T20:51:28+00:00\" \/>\n<meta name=\"author\" content=\"Frecan\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Frecan\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.frecan.es\/blog\/en\/flagship-store-paris-de-florim\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.frecan.es\/blog\/en\/flagship-store-paris-de-florim\/\"},\"author\":{\"name\":\"Frecan\",\"@id\":\"https:\/\/www.frecan.es\/blog\/en\/#\/schema\/person\/eecbdddf4fc3d5ee61f34db3cfb262a4\"},\"headline\":\"Experimenta posibilidades ilimitadas, de la m\u00e1s alta calidad, para la planificaci\u00f3n de su hogar en el coraz\u00f3n de Par\u00eds.\",\"datePublished\":\"2022-11-29T20:51:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.frecan.es\/blog\/en\/flagship-store-paris-de-florim\/\"},\"wordCount\":400,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.frecan.es\/blog\/en\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.frecan.es\/blog\/en\/flagship-store-paris-de-florim\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.frecan.es\/blog\/wp-content\/uploads\/2022\/11\/florim-paris-campana-superficie-flow-frecan.jpg\",\"articleSection\":[\"Dealers\",\"Design kitchens\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.frecan.es\/blog\/en\/flagship-store-paris-de-florim\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.frecan.es\/blog\/en\/flagship-store-paris-de-florim\/\",\"url\":\"https:\/\/www.frecan.es\/blog\/en\/flagship-store-paris-de-florim\/\",\"name\":\"Experimenta posibilidades ilimitadas, de la m\u00e1s alta calidad, para la planificaci\u00f3n de su hogar en el coraz\u00f3n de Par\u00eds. - Blog de Frecan\",\"isPartOf\":{\"@id\":\"https:\/\/www.frecan.es\/blog\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.frecan.es\/blog\/en\/flagship-store-paris-de-florim\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.frecan.es\/blog\/en\/flagship-store-paris-de-florim\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.frecan.es\/blog\/wp-content\/uploads\/2022\/11\/florim-paris-campana-superficie-flow-frecan.jpg\",\"datePublished\":\"2022-11-29T20:51:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.frecan.es\/blog\/en\/flagship-store-paris-de-florim\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.frecan.es\/blog\/en\/flagship-store-paris-de-florim\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.frecan.es\/blog\/en\/flagship-store-paris-de-florim\/#primaryimage\",\"url\":\"https:\/\/www.frecan.es\/blog\/wp-content\/uploads\/2022\/11\/florim-paris-campana-superficie-flow-frecan.jpg\",\"contentUrl\":\"https:\/\/www.frecan.es\/blog\/wp-content\/uploads\/2022\/11\/florim-paris-campana-superficie-flow-frecan.jpg\",\"width\":1134,\"height\":1134,\"caption\":\"Flagship Store Paris de Florim - Campana superficie\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.frecan.es\/blog\/en\/flagship-store-paris-de-florim\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Cover page\",\"item\":\"https:\/\/www.frecan.es\/blog\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Experimenta posibilidades ilimitadas, de la m\u00e1s alta calidad, para la planificaci\u00f3n de su hogar en el coraz\u00f3n de Par\u00eds.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.frecan.es\/blog\/en\/#website\",\"url\":\"https:\/\/www.frecan.es\/blog\/en\/\",\"name\":\"Blog de Frecan\",\"description\":\"Craftsmanship, technology and avant-garde in the heart of your kitchen\",\"publisher\":{\"@id\":\"https:\/\/www.frecan.es\/blog\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.frecan.es\/blog\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.frecan.es\/blog\/en\/#organization\",\"name\":\"Frecan\",\"url\":\"https:\/\/www.frecan.es\/blog\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.frecan.es\/blog\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.frecan.es\/blog\/wp-content\/uploads\/2016\/02\/logo-frecan.png\",\"contentUrl\":\"https:\/\/www.frecan.es\/blog\/wp-content\/uploads\/2016\/02\/logo-frecan.png\",\"width\":250,\"height\":27,\"caption\":\"Frecan\"},\"image\":{\"@id\":\"https:\/\/www.frecan.es\/blog\/en\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.frecan.es\/blog\/en\/#\/schema\/person\/eecbdddf4fc3d5ee61f34db3cfb262a4\",\"name\":\"Frecan\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.frecan.es\/blog\/en\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/5f22fe11c8d7e915c3e67301f8a5068f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/5f22fe11c8d7e915c3e67301f8a5068f?s=96&d=mm&r=g\",\"caption\":\"Frecan\"},\"sameAs\":[\"http:\/\/www.frecan.es\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Experimenta posibilidades ilimitadas, de la m\u00e1s alta calidad, para la planificaci\u00f3n de su hogar en el coraz\u00f3n de Par\u00eds. - Blog de Frecan","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.frecan.es\/blog\/en\/flagship-store-paris-de-florim\/","og_locale":"en_US","og_type":"article","og_title":"Experimenta posibilidades ilimitadas, de la m\u00e1s alta calidad, para la planificaci\u00f3n de su hogar en el coraz\u00f3n de Par\u00eds. - Blog de Frecan","og_description":"Redise\u00f1ar o dise\u00f1ar tu casa es uno de los proyectos m\u00e1s grandes e importantes. Es emocionante, pero a la vez tambi\u00e9n puede ser desalentador si no sabes c\u00f3mo empezar.","og_url":"https:\/\/www.frecan.es\/blog\/en\/flagship-store-paris-de-florim\/","og_site_name":"Blog de Frecan","article_published_time":"2022-11-29T20:51:28+00:00","author":"Frecan","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Frecan","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.frecan.es\/blog\/en\/flagship-store-paris-de-florim\/#article","isPartOf":{"@id":"https:\/\/www.frecan.es\/blog\/en\/flagship-store-paris-de-florim\/"},"author":{"name":"Frecan","@id":"https:\/\/www.frecan.es\/blog\/en\/#\/schema\/person\/eecbdddf4fc3d5ee61f34db3cfb262a4"},"headline":"Experimenta posibilidades ilimitadas, de la m\u00e1s alta calidad, para la planificaci\u00f3n de su hogar en el coraz\u00f3n de Par\u00eds.","datePublished":"2022-11-29T20:51:28+00:00","mainEntityOfPage":{"@id":"https:\/\/www.frecan.es\/blog\/en\/flagship-store-paris-de-florim\/"},"wordCount":400,"commentCount":0,"publisher":{"@id":"https:\/\/www.frecan.es\/blog\/en\/#organization"},"image":{"@id":"https:\/\/www.frecan.es\/blog\/en\/flagship-store-paris-de-florim\/#primaryimage"},"thumbnailUrl":"https:\/\/www.frecan.es\/blog\/wp-content\/uploads\/2022\/11\/florim-paris-campana-superficie-flow-frecan.jpg","articleSection":["Dealers","Design kitchens"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.frecan.es\/blog\/en\/flagship-store-paris-de-florim\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.frecan.es\/blog\/en\/flagship-store-paris-de-florim\/","url":"https:\/\/www.frecan.es\/blog\/en\/flagship-store-paris-de-florim\/","name":"Experimenta posibilidades ilimitadas, de la m\u00e1s alta calidad, para la planificaci\u00f3n de su hogar en el coraz\u00f3n de Par\u00eds. - Blog de Frecan","isPartOf":{"@id":"https:\/\/www.frecan.es\/blog\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.frecan.es\/blog\/en\/flagship-store-paris-de-florim\/#primaryimage"},"image":{"@id":"https:\/\/www.frecan.es\/blog\/en\/flagship-store-paris-de-florim\/#primaryimage"},"thumbnailUrl":"https:\/\/www.frecan.es\/blog\/wp-content\/uploads\/2022\/11\/florim-paris-campana-superficie-flow-frecan.jpg","datePublished":"2022-11-29T20:51:28+00:00","breadcrumb":{"@id":"https:\/\/www.frecan.es\/blog\/en\/flagship-store-paris-de-florim\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.frecan.es\/blog\/en\/flagship-store-paris-de-florim\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.frecan.es\/blog\/en\/flagship-store-paris-de-florim\/#primaryimage","url":"https:\/\/www.frecan.es\/blog\/wp-content\/uploads\/2022\/11\/florim-paris-campana-superficie-flow-frecan.jpg","contentUrl":"https:\/\/www.frecan.es\/blog\/wp-content\/uploads\/2022\/11\/florim-paris-campana-superficie-flow-frecan.jpg","width":1134,"height":1134,"caption":"Flagship Store Paris de Florim - Campana superficie"},{"@type":"BreadcrumbList","@id":"https:\/\/www.frecan.es\/blog\/en\/flagship-store-paris-de-florim\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Cover page","item":"https:\/\/www.frecan.es\/blog\/en\/"},{"@type":"ListItem","position":2,"name":"Experimenta posibilidades ilimitadas, de la m\u00e1s alta calidad, para la planificaci\u00f3n de su hogar en el coraz\u00f3n de Par\u00eds."}]},{"@type":"WebSite","@id":"https:\/\/www.frecan.es\/blog\/en\/#website","url":"https:\/\/www.frecan.es\/blog\/en\/","name":"Blog de Frecan","description":"Craftsmanship, technology and avant-garde in the heart of your kitchen","publisher":{"@id":"https:\/\/www.frecan.es\/blog\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.frecan.es\/blog\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.frecan.es\/blog\/en\/#organization","name":"Frecan","url":"https:\/\/www.frecan.es\/blog\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.frecan.es\/blog\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.frecan.es\/blog\/wp-content\/uploads\/2016\/02\/logo-frecan.png","contentUrl":"https:\/\/www.frecan.es\/blog\/wp-content\/uploads\/2016\/02\/logo-frecan.png","width":250,"height":27,"caption":"Frecan"},"image":{"@id":"https:\/\/www.frecan.es\/blog\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.frecan.es\/blog\/en\/#\/schema\/person\/eecbdddf4fc3d5ee61f34db3cfb262a4","name":"Frecan","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.frecan.es\/blog\/en\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/5f22fe11c8d7e915c3e67301f8a5068f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5f22fe11c8d7e915c3e67301f8a5068f?s=96&d=mm&r=g","caption":"Frecan"},"sameAs":["http:\/\/www.frecan.es\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.frecan.es\/blog\/en\/wp-json\/wp\/v2\/posts\/7919","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.frecan.es\/blog\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.frecan.es\/blog\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.frecan.es\/blog\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.frecan.es\/blog\/en\/wp-json\/wp\/v2\/comments?post=7919"}],"version-history":[{"count":0,"href":"https:\/\/www.frecan.es\/blog\/en\/wp-json\/wp\/v2\/posts\/7919\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.frecan.es\/blog\/en\/wp-json\/wp\/v2\/media\/7911"}],"wp:attachment":[{"href":"https:\/\/www.frecan.es\/blog\/en\/wp-json\/wp\/v2\/media?parent=7919"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.frecan.es\/blog\/en\/wp-json\/wp\/v2\/categories?post=7919"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.frecan.es\/blog\/en\/wp-json\/wp\/v2\/tags?post=7919"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}